{"id":11129,"date":"2022-01-13T07:00:00","date_gmt":"2022-01-13T06:00:00","guid":{"rendered":"https:\/\/xd3kj9bvqee.preview.infomaniak.website\/?p=11129"},"modified":"2022-01-13T00:17:54","modified_gmt":"2022-01-12T23:17:54","slug":"as-partes-interessadas-da-industria-cosmetica-unem-se-para-criar-uma-bts-especializada","status":"publish","type":"post","link":"https:\/\/www.industries-cosmetiques.fr\/pt\/as-partes-interessadas-da-industria-cosmetica-unem-se-para-criar-uma-bts-especializada\/","title":{"rendered":"Os actores da ind\u00fastria cosm\u00e9tica unem for\u00e7as para criar uma BTS especializada"},"content":{"rendered":"<p>V\u00e1rios l\u00edderes franceses da embalagem de pl\u00e1stico (Alb\u00e9a, Aptar, Texen, Medicos e PRP Cr\u00e9ation) associaram-se \u00e0 Polyvia Formation para criar um BTS especializado na inje\u00e7\u00e3o de pl\u00e1stico para cosm\u00e9ticos, o BTS Europlastics et Composites option Cosm\u00e9tique. O objetivo \u00e9 formar jovens e desenvolver as suas compet\u00eancias, adaptando o conte\u00fado da sua forma\u00e7\u00e3o \u00e0s necessidades da ind\u00fastria de embalagens de cosm\u00e9ticos.&nbsp;<\/p>\n\n\n\n<p>Este BTS (Advanced Technician's Certificate) forma os estudantes para profiss\u00f5es t\u00e9cnicas que s\u00e3o muito procuradas na ind\u00fastria atual. Um grande n\u00famero de postos de trabalho est\u00e1 atualmente dispon\u00edvel nos v\u00e1rios locais de produ\u00e7\u00e3o de todos os intervenientes industriais.&nbsp;<\/p><div class=\"indus-dans-articles indus-entity-placement\" style=\"text-align: center;display: flex;justify-content: center;\" id=\"indus-3705229615\"><div class=\"indus-adlabel\">Publicidade<\/div><div id=\"indus-308911528\"><a data-bid=\"1\" data-no-instant=\"1\" href=\"https:\/\/www.industries-cosmetiques.fr\/pt\/ad\/25262\" rel=\"noopener nofollow\" class=\"notrack\" target=\"_blank\" aria-label=\"site-industries-cosmetiques Imagem promocional das capas recicl\u00e1veis para livros \u00abprot\u00e8ge-livre\u00bb da Handicap International, com o Homem-Aranha. O texto destaca que, por cada compra, \u00e9 doado 1 \u20ac. A embalagem est\u00e1 dispon\u00edvel em v\u00e1rios tamanhos. Fundo azul com texto branco. Dispon\u00edvel para o ano letivo de 2026.\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.industries-cosmetiques.fr\/wp-content\/uploads\/2026\/06\/KPL_2026_FORMAT-META-300x300px.png\" alt=\"site-industries-cosmetiques Imagem promocional das capas recicl\u00e1veis para livros \u00abprot\u00e8ge-livre\u00bb da Handicap International, com o Homem-Aranha. O texto destaca que, por cada compra, \u00e9 doado 1 \u20ac. A embalagem est\u00e1 dispon\u00edvel em v\u00e1rios tamanhos. Fundo azul com texto branco. Dispon\u00edvel para o ano letivo de 2026.\"  srcset=\"https:\/\/www.industries-cosmetiques.fr\/wp-content\/uploads\/2026\/06\/KPL_2026_FORMAT-META-300x300px.png 300w, https:\/\/www.industries-cosmetiques.fr\/wp-content\/uploads\/2026\/06\/KPL_2026_FORMAT-META-300x300px-150x150.png 150w, https:\/\/www.industries-cosmetiques.fr\/wp-content\/uploads\/2026\/06\/KPL_2026_FORMAT-META-300x300px-12x12.png 12w\" sizes=\"(max-width: 300px) 100vw, 300px\" class=\"no-lazyload\" width=\"300\" height=\"300\"   \/><\/a><\/div><\/div>\n\n\n\n<p>Dispon\u00edvel em Parcoursup, esta BTS ser\u00e1 destinada aos alunos do \u00faltimo ano dos liceus t\u00e9cnicos e gerais a partir do in\u00edcio do ano letivo de 2022-2023.&nbsp;<\/p>\n\n\n\n<p><strong>As vantagens desta BTS <\/strong>&nbsp;<\/p>\n\n\n\n<p>No \u00e2mbito deste BTS, os estudantes alternar\u00e3o entre uma unidade industrial regional e um centro de forma\u00e7\u00e3o da Polyvia, para aprenderem a teoria e a pr\u00e1tica da produ\u00e7\u00e3o de pe\u00e7as de pl\u00e1stico ou comp\u00f3sitos, os desafios da industrializa\u00e7\u00e3o de novos produtos e processos e a otimiza\u00e7\u00e3o cont\u00ednua.&nbsp;<\/p>\n\n\n\n<p>\u2192 Os estudantes beneficiar\u00e3o de um acompanhamento personalizado sobre as profiss\u00f5es da cosm\u00e9tica durante a sua estadia na empresa, gra\u00e7as a especialistas reconhecidos na profiss\u00e3o que os formar\u00e3o e lhes permitir\u00e3o trabalhar em situa\u00e7\u00f5es reais.&nbsp;<\/p>\n\n\n\n<p>\u2192 No primeiro ano, os estudantes passam 3 a 4 semanas de est\u00e1gio em Fran\u00e7a, numa unidade industrial diferente daquela onde est\u00e3o a frequentar o curso sandu\u00edche.&nbsp;<\/p>\n\n\n\n<p>\u2192 No segundo ano, ter\u00e3o a oportunidade de efetuar um est\u00e1gio no estrangeiro com uma dura\u00e7\u00e3o m\u00e1xima de 4 semanas.&nbsp;<\/p>\n\n\n\n<p>\u2192 No final do programa de trabalho-estudo de dois anos, pode ser oferecido aos estudantes um emprego numa das nossas empresas parceiras.&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Plusieurs leaders fran\u00e7ais de l\u2019emballage plastique (Alb\u00e9a, Aptar, Texen, Medicos et PRP Cr\u00e9ation) se sont associ\u00e9s \u00e0 Polyvia Formation pour construire un BTS sp\u00e9cialis\u00e9 dans l\u2019injection plastique pour la cosm\u00e9tique, &nbsp;le BTS Europlastics et Composites option Cosm\u00e9tique. L\u2019objectif \u00e9tant de former des jeunes et de d\u00e9velopper leurs comp\u00e9tences en adaptant le contenu de leur formation [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":11133,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"external_url":"","footnotes":""},"categories":[57],"tags":[61],"class_list":{"0":"post-11129","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-packaging","8":"tag-info-marche"},"acf":{"nc":"","nc2":"","nc3":"","nc4":"","nc5":"","nom_url":"","lien_url":""},"_links":{"self":[{"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/posts\/11129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/comments?post=11129"}],"version-history":[{"count":0,"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/posts\/11129\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/media\/11133"}],"wp:attachment":[{"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/media?parent=11129"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/categories?post=11129"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.industries-cosmetiques.fr\/pt\/wp-json\/wp\/v2\/tags?post=11129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}